{"id":3,"date":"2023-05-02T14:02:38","date_gmt":"2023-05-02T12:02:38","guid":{"rendered":"http:\/\/vl-e.fr\/?page_id=3"},"modified":"2023-12-20T16:07:05","modified_gmt":"2023-12-20T15:07:05","slug":"politique-de-confidentialite-vl-e","status":"publish","type":"page","link":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/","title":{"rendered":"Politique de confidentialit\u00e9 VL-e"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb3.22&Prime;][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.6&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h2>Mentions l\u00e9gales et donn\u00e9es personnelles\u00a0VL-e<\/h2>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<div class=\"et_pb_section et_pb_section_0 et_section_regular\">\n<div class=\"et_pb_row et_pb_row_0\">\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_0  et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1  et_pb_text_align_justified et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3><b>\u00c9diteur du site VL-e :<\/b><\/h3>\n<p>PRO OFFICE GESTION \u2013 \u00a0MADAME RAMET MYRIAM \u2013 CREATION DE SITES WEB<\/p>\n<p>Immatriculation au RCS, num\u00e9ro : 947.954.681 R.C.S Boulogne-sur-mer<br \/> Date immatriculation RCS : 09\/01\/2023<br \/> Adresse du si\u00e8ge social : All\u00e9e de Bretagne \u2013 R\u00e9sidence Solymar 2 \u2013 Appart 22 \u2013 62155 Merlimont<br \/> Activit\u00e9 : Autres services personnels n.c.a. (9609Z)<br \/> Forme juridique : SASU \u2013 Soci\u00e9t\u00e9 par action simplifi\u00e9es unipersonnelle<br \/> Capital social : 1 500\u20ac<br \/> Dur\u00e9e de la personne morale : jusqu\u2019au 09\/01\/2122<\/p>\n<p>PRO OFFICE GESTION<br \/> All\u00e9e de Bretagne<br \/> R\u00e9sidence Solymar 2 \u2013 Appartement 22<br \/> 62155 Merlimont<\/p>\n<p>Site internet :<a href=\"https:\/\/weekendopale.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0https:\/\/pro-officegestion.fr\/<\/a><br \/> T\u00e9l. : +33 (0)7.67.16.90.02<br \/> Email : contact@pro-officegestion.fr<\/p>\n<h3><b>Responsable, Gestion, Direction, Administration, Controle, ou Membres :<\/b><\/h3>\n<p><strong>VL-e<\/strong><\/p>\n<p>LARD\u00c9 Vincent<\/p>\n<p>Nationalit\u00e9 : France<\/p>\n<p>Adresse : 137 avenue de Verdun<br \/> 62780 Cucq<\/p>\n<h3><b>Conception et production :<\/b><\/h3>\n<p>Madame Ramet Myriam PRO-OFFICE GESTION<\/p>\n<h3><b>Cr\u00e9dits photos et vid\u00e9os :<\/b><\/h3>\n<p>Photos et vid\u00e9os de Pro-Office Gestion<\/p>\n<p>\u00a9pro-officegestion<\/p>\n<p>Myriam Ramet<\/p>\n<h3><b>Respect de la vie priv\u00e9e :<\/b><\/h3>\n<p>Droit d\u2019acc\u00e8s et de modification des donn\u00e9es vous concernant :<\/p>\n<p>Il s\u2019agit de la politique de respect de la vie priv\u00e9e adopt\u00e9e par VL-e.<\/p>\n<p>Vous disposez d\u2019un droit d\u2019acc\u00e8s, de modification, de rectification et de suppression des donn\u00e9es qui vous concernent (art.34 de la loi \u00ab Informatique et Libert\u00e9s \u00bb n\u00ba 78-17 du 16 janvier 1978). Pour l\u2019exercer, adressez-vous par courriel \u00e0 : contact@officegestion.fr Par \u00ab Information Personnelle \u00bb, il faut entendre toute information qui permet d\u2019identifier une personne. Il s\u2019agira le plus souvent d\u2019un nom, d\u2019une adresse, d\u2019un num\u00e9ro de t\u00e9l\u00e9phone ou d\u2019une adresse \u00e9lectronique.<\/p>\n<h3><strong>Donn\u00e9es personnelles et cookies :<\/strong><\/h3>\n<p>VL-e respecte les pr\u00e9occupations des utilisateurs concernant la confidentialit\u00e9 des renseignements et informations personnels fournis. En qualit\u00e9 de responsable de traitement au titre de la Loi Informatique et Libert\u00e9s du 6 janvier 1978 modifi\u00e9e en 2004 et de la directive europ\u00e9enne du 24 octobre 1995 (ci-apr\u00e8s, la \u00ab\u00a0Loi Informatique et Libert\u00e9s\u00a0\u00bb) VL-e est susceptible de collecter des donn\u00e9es nominatives (noms, pr\u00e9noms, coordonn\u00e9es\u2026) ou non nominatives (pr\u00e9f\u00e9rences, informations favorites\u2026) lors des visites de l\u2019utilisateur sur son site internet (ci-apr\u00e8s le \u00ab\u00a0Site\u00a0\u00bb) afin d\u2019\u00eatre en mesure de l\u2019identifier, de lui proposer des services personnalis\u00e9s ou encore afin d\u2019am\u00e9liorer le Site et d\u2019\u00eatre \u00e0 son \u00e9coute.<\/p>\n<p>1 \u2013 DESTINATAIRES DES DONN\u00c9ES\u00a0COLLECT\u00c9ES VL-e est destinataire des donn\u00e9es. En tout \u00e9tat de cause, VL-e ne transmet les donn\u00e9es personnelles des utilisateurs \u00e0 un tiers que lorsque :<\/p>\n<p>\u2013 l\u2019utilisateur a donn\u00e9 son accord pr\u00e9alable pour le partage de ces informations,<\/p>\n<p>\u2013 VL-e doit partager ces informations avec des tiers pour fournir le service attendu,<\/p>\n<p>\u2013 VL-e souhaite faire b\u00e9n\u00e9ficier \u00e0 l\u2019utilisateur des offres partenaires.<\/p>\n<p>\u2013 VL-e est somm\u00e9 par une autorit\u00e9 judiciaire ou toute autre autorit\u00e9 administrative de lui communiquer les informations.<\/p>\n<p>VL-e peut \u00e9galement communiquer les donn\u00e9es personnelles des utilisateurs \u00e0 des prestataires tiers dans le cadre d\u2019\u00e9tudes statistiques de l\u2019utilisation du Site et \u00e0 des fins d\u2019optimisation du Site. Dans ce cadre, les donn\u00e9es personnelles des utilisateurs seront anonymes.<\/p>\n<p>2 \u2013 FINALIT\u00c9S\u00a0DE LA COLLECTE DES\u00a0DONN\u00c9ES Au travers du Site :<\/p>\n<p>VL-e collecte les donn\u00e9es concernant l\u2019utilisateur qui sont strictement n\u00e9cessaires aux finalit\u00e9s suivantes :<\/p>\n<p>\u2013 mise \u00e0 disposition et personnalisation du Site<\/p>\n<p>\u2013 offre commerciale et promotionnelle de VL-e.<\/p>\n<p>VL-e s\u2019engage \u00e0 traiter et \u00e0 conserver toute information personnelle confi\u00e9e par l\u2019utilisateur dans le respect des dispositions de la Loi Informatique et Libert\u00e9s\u00a0et ce uniquement afin de tenir l\u2019utilisateur inform\u00e9 de l\u2019actualit\u00e9 de VL-e\u00a0et de lui faire b\u00e9n\u00e9ficier en priorit\u00e9 d\u2019offres de biens et services li\u00e9s \u00e0 l\u2019activit\u00e9 de VL-e.<\/p>\n<p>3 \u2013 CONSERVATION DES DONN\u00c9ES\u00a0ET\u00a0S\u00c9CURIT\u00c9 Les donn\u00e9es sont conserv\u00e9es pendant une dur\u00e9e qui n\u2019exc\u00e8de pas la dur\u00e9e n\u00e9cessaire aux finalit\u00e9s pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es : pour la gestion de l\u2019abonnement \u00e0 la newsletter, les donn\u00e9es seront conserv\u00e9es aussi longtemps que l\u2019abonnement est actif et toutes les donn\u00e9es seront supprim\u00e9es dans un d\u00e9lai de 1 mois \u00e0 compter de la d\u00e9sinscription d\u2019un utilisateur ; Pour les autres donn\u00e9es elles seront conserv\u00e9es dans un d\u00e9lai de 2 ans. VL-e s\u2019est efforc\u00e9 de mettre en place toutes pr\u00e9cautions utiles pour pr\u00e9server la confidentialit\u00e9 et la s\u00e9curit\u00e9 des donn\u00e9es personnelles trait\u00e9es et emp\u00eacher qu\u2019elles ne soient d\u00e9form\u00e9es, endommag\u00e9es, d\u00e9truites ou que des tiers non autoris\u00e9s y aient acc\u00e8s. Les mesures de s\u00e9curit\u00e9 technique et organisationnelle conformes \u00e0 l\u2019\u00e9tat de l\u2019art, notamment pour ce qui rel\u00e8ve des syst\u00e8mes d\u2019information, ont \u00e9t\u00e9 instaur\u00e9es. Cependant, VL-e ne ma\u00eetrise pas tous les risques li\u00e9s au fonctionnement d\u2019internet et attire l\u2019attention des utilisateurs sur l\u2019existence d\u2019\u00e9ventuels risques inh\u00e9rents \u00e0 son utilisation et \u00e0 son fonctionnement.<\/p>\n<p>4 \u2013 DROITS DES UTILISATEURS :<\/p>\n<p>L\u2019utilisateur est inform\u00e9 qu\u2019il dispose, conform\u00e9ment \u00e0 Loi Informatique et Libert\u00e9s,\u00a0\u00e0 tout moment d\u2019un droit d\u2019acc\u00e8s, de mise \u00e0 jour, de rectification et de suppression de ses donn\u00e9es personnelles en adressant une requ\u00eate (en indiquant pr\u00e9cis\u00e9ment l\u2019objet de sa demande) par Internet \u00e0 l\u2019adresse suivante : <a href=\"mailto:contact@weekendopale.fr\">contact@vl-e.fr<\/a> Ou par courrier \u00e0 l\u2019adresse suivante :<\/p>\n<p>137 avenue de Verdun<br \/> 62780 Cucq que VL-e s\u2019engage \u00e0 traiter dans un d\u00e9lai de sept jours ouvr\u00e9s. L\u2019utilisateur est inform\u00e9 qu\u2019il dispose, conform\u00e9ment \u00e0 Loi Informatique et Libert\u00e9s,\u00a0\u00e0 tout moment d\u2019un droit de s\u2019opposer, pour des motifs l\u00e9gitimes, \u00e0 ce que des donn\u00e9es \u00e0 caract\u00e8re personnel le concernant fassent l\u2019objet d\u2019un traitement.<\/p>\n<p>5 \u2013 COOKIES, DONN\u00c9ES\u00a0DE NAVIGATION ET LOCALISATION :<\/p>\n<p>Lors de l\u2019acc\u00e8s au Site, et apr\u00e8s acceptation de la poursuite de la navigation par l\u2019utilisateur, un cookie peut \u00eatre install\u00e9 et \u00eatre conserv\u00e9 pour une dur\u00e9e maximale de 13 mois en m\u00e9moire ou sur le disque dur de l\u2019utilisateur, afin de faciliter sa navigation. Un cookie ne permet pas d\u2019identifier mais est un \u00e9l\u00e9ment qui sert \u00e0 enregistrer des informations relatives \u00e0 la navigation sur le Site (les pages consult\u00e9es, la date et l\u2019heure de la consultation, etc.) Les Cookies \u00e9mis permettent :<\/p>\n<ul>\n<li>de faciliter l\u2019exp\u00e9rience de navigation sur le Site, d\u2019am\u00e9liorer l\u2019int\u00e9r\u00eat et l\u2019ergonomie des services consult\u00e9s sur le Site, et d\u2019adapter la pr\u00e9sentation du Site\u00a0;<\/li>\n<li>de m\u00e9moriser des informations relatives \u00e0 un formulaire que\u00a0l\u2019utilisateur a rempli sur le Site (inscription ou acc\u00e8s au compte) ou \u00e0 des produits choisis sur le Site (contenu d\u2019un panier de commande, etc.) ;<\/li>\n<li>de comptabiliser le nombre de visites sur le Site, et de ce fait et d\u2019\u00e9tablir des statistiques.<\/li>\n<\/ul>\n<p>Chaque utilisateur peut refuser l\u2019enregistrement des cookies en modifiant les param\u00e8tres de son navigateur internet. Cette op\u00e9ration entra\u00eenera cependant la suppression de tous les cookies utilis\u00e9s par le navigateur, y compris ceux employ\u00e9s par d\u2019autres sites web, ce qui peut conduire \u00e0 l\u2019alt\u00e9ration ou la perte de certains r\u00e9glages ou informations. La suppression des cookies peut \u00eatre de nature \u00e0 modifier, voire \u00e0 rendre difficile la navigation sur le Site. Pour la gestion des cookies et des choix des utilisateurs, la configuration de chaque navigateur est diff\u00e9rente. Elle est d\u00e9crite dans le menu d\u2019aide du navigateur, qui permettra \u00e0 l\u2019utilisateur de savoir de quelle mani\u00e8re modifier ses souhaits en mati\u00e8re de cookies.<\/p>\n<ul>\n<li>Pour Internet Explorer\u2122 :\u00a0<a href=\"https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies\">https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a>,<\/li>\n<li>Pour Safari\u2122 :\u00a0<a href=\"https:\/\/support.apple.com\/fr-fr\/guide\/safari\/manage-cookies-and-website-data-sfri11471\/mac\">https:\/\/support.apple.com\/fr-fr\/guide\/safari\/manage-cookies-and-website-data-sfri11471\/mac<\/a>,<\/li>\n<li>Pour Chrome\u2122 :\u00a0<a href=\"https:\/\/support.google.com\/chrome\/answer\/2392709?hl=fr&amp;ref_topic=7438008\">https:\/\/support.google.com\/chrome\/answer\/2392709?hl=fr&amp;ref_topic=7438008<\/a>,<\/li>\n<li>Pour Firefox\u2122\u00a0:\u00a0<a href=\"https:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences\">https:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences<\/a>,<\/li>\n<li>Pour Opera\u2122 :\u00a0<a href=\"http:\/\/help.opera.com\/Windows\/10.20\/fr\/cookies.html\">http:\/\/help.opera.com\/Windows\/10.20\/fr\/cookies.html<\/a><\/li>\n<\/ul>\n<h3><strong>S\u00e9curit\u00e9 et confidentialit\u00e9 sur le r\u00e9seau :<\/strong><\/h3>\n<p>Les messages que vous nous ferez parvenir par l\u2019interm\u00e9diaire d\u2019Internet peuvent \u00eatre intercept\u00e9s sur le r\u00e9seau. Jusqu\u2019\u00e0 ce qu\u2019ils nous parviennent, leur confidentialit\u00e9 ne peut \u00eatre garantie.<\/p>\n<p>Assurez-vous de ne pas divulguer d\u2019informations personnelles ou confidentielles inutiles, sensibles ou provenant de tiers. De plus, l\u2019indication de la provenance des messages \u00e9lectroniques que nous recevons peut \u00eatre falsifi\u00e9e. Par cons\u00e9quent, si vous souhaitez nous communiquer de telles informations, utilisez imp\u00e9rativement la voie postale. En cons\u00e9quence, aucune plainte, d\u00e9claration ou demande de conseil transmise par message Internet ne sera prise en compte.<\/p>\n<p>Veuillez formuler vos demandes exclusivement par voie postale. Pour obtenir plus de renseignements sur les proc\u00e9dures \u00e0 suivre ou sur des dossiers en cours d\u2019instruction, veuillez prendre contact avec la soci\u00e9t\u00e9 VL-e par \u00e9crit.<\/p>\n<h3><b>Respect des droits d\u2019auteur :<\/b><\/h3>\n<p>Utilisation des informations du site et droits d\u2019auteur :<\/p>\n<p>L\u2019utilisation de tout document provenant du site de la soci\u00e9t\u00e9 VL-e n\u2019est autoris\u00e9e qu\u2019\u00e0 titre d\u2019information pour un usage priv\u00e9. Toute utilisation qui pourrait \u00eatre effectu\u00e9e \u00e0 d\u2019autres fins est express\u00e9ment interdite.<\/p>\n<p>La soci\u00e9t\u00e9 VL-e s\u2019efforce d\u2019assurer au mieux de ses possibilit\u00e9s, l\u2019exactitude et la mise \u00e0 jour des informations diffus\u00e9es sur ce site, dont elle se r\u00e9serve le droit de corriger, \u00e0 tout moment et sans pr\u00e9avis, le contenu.<\/p>\n<p>Aussi, elle avertit le visiteur qu\u2019il lui appartient de v\u00e9rifier l\u2019information par d\u2019autres moyens, y compris en contactant la soci\u00e9t\u00e9.<\/p>\n<p>En cons\u00e9quence, la soci\u00e9t\u00e9 VL-e d\u00e9cline toute responsabilit\u00e9 : pour toute impr\u00e9cision, inexactitude ou omission portant sur des informations disponibles sur le site ; pour tous dommages r\u00e9sultant d\u2019une intrusion frauduleuse d\u2019un tiers ayant entra\u00een\u00e9 une modification des informations mises \u00e0 la disposition sur le site ; et plus g\u00e9n\u00e9ralement pour tous dommages, directs ou indirects, qu\u2019elles qu\u2019en soient les causes, origines, nature ou cons\u00e9quences, provoqu\u00e9s \u00e0 raison de l\u2019acc\u00e8s de quiconque au site ou de l\u2019impossibilit\u00e9 d\u2019y acc\u00e9der, de m\u00eame que l\u2019utilisation du site et\/ou du cr\u00e9dit accord\u00e9 \u00e0 une quelconque information provenant directement ou indirectement de ce dernier.<\/p>\n<p>Par ailleurs, sauf mention contraire, les droits de propri\u00e9t\u00e9 intellectuelle sur les documents contenus dans le site et chacun des \u00e9l\u00e9ments cr\u00e9\u00e9s pour ce site sont la propri\u00e9t\u00e9 exclusive de la soci\u00e9t\u00e9 VL-e ou de ses fournisseurs, ceux-ci ne conc\u00e9dant aucune licence, ni aucun droit que celui de consulter le site.<\/p>\n<p>La reproduction de tous documents publi\u00e9s sur le site est seulement autoris\u00e9e aux fins exclusives d\u2019informations pour un usage personnel et priv\u00e9, toute reproduction et toute utilisation de copies r\u00e9alis\u00e9es \u00e0 d\u2019autres fins \u00e9tant express\u00e9ment interdite.<\/p>\n<p>Toutes les marques cit\u00e9es dans ce site appartiennent \u00e0 leurs compagnies respectives.<\/p>\n<p>Tous les produits, logos, et images cit\u00e9s dans les pages de ce site sont la propri\u00e9t\u00e9 de leur marque respective.<\/p>\n<h3>Informations d\u2019ordre technique :<\/h3>\n<p>Le pr\u00e9sent site est accessible 24 heures sur 24 et 7 jours sur 7, \u00e0 l\u2019exception des cas de force majeure, difficult\u00e9s informatiques, difficult\u00e9s li\u00e9es \u00e0 la structure des r\u00e9seaux de communication ou difficult\u00e9s d\u2019ordre technique. Pour des raisons de maintenance pourra interrompre \u00e0 tout moment le site.<\/p>\n<h3><strong>Application de la loi Fran\u00e7aise :<\/strong><\/h3>\n<p>Le non-respect des pr\u00e9sentes dispositions expose le contrevenant \u00e0 des poursuites et \u00e0 des sanctions p\u00e9nales. Le pr\u00e9sent document est r\u00e9gi et interpr\u00e9t\u00e9 selon le droit Fran\u00e7ais et rel\u00e8ve de la comp\u00e9tence exclusive des Tribunaux Fran\u00e7ais. Si l\u2019une des dispositions du pr\u00e9sent texte s\u2019av\u00e9rait nulle, non valide ou sans effet juridique, toutes les autres dispositions demeureraient applicables.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales et donn\u00e9es personnelles\u00a0VL-e \u00c9diteur du site VL-e : PRO OFFICE GESTION \u2013 \u00a0MADAME RAMET MYRIAM \u2013 CREATION DE SITES WEB Immatriculation au RCS, num\u00e9ro : 947.954.681 R.C.S Boulogne-sur-mer Date immatriculation RCS : 09\/01\/2023 Adresse du si\u00e8ge social : All\u00e9e de Bretagne \u2013 R\u00e9sidence Solymar 2 \u2013 Appart 22 \u2013 62155 Merlimont Activit\u00e9 : Autres services personnels n.c.a. (9609Z) Forme juridique : SASU \u2013 Soci\u00e9t\u00e9 par action simplifi\u00e9es unipersonnelle Capital social : 1 500\u20ac Dur\u00e9e de la personne morale : jusqu\u2019au 09\/01\/2122 PRO OFFICE GESTION All\u00e9e de Bretagne R\u00e9sidence Solymar 2 \u2013 Appartement 22 62155 Merlimont Site internet :\u00a0https:\/\/pro-officegestion.fr\/ T\u00e9l. : +33 (0)7.67.16.90.02 Email : contact@pro-officegestion.fr Responsable, Gestion, Direction, Administration, Controle, ou Membres : VL-e LARD\u00c9 Vincent Nationalit\u00e9 : France Adresse : 137 avenue de Verdun 62780 Cucq Conception et production : Madame Ramet Myriam PRO-OFFICE GESTION Cr\u00e9dits photos et vid\u00e9os : Photos et vid\u00e9os de Pro-Office Gestion \u00a9pro-officegestion Myriam Ramet Respect de la vie priv\u00e9e : Droit d\u2019acc\u00e8s et de modification des donn\u00e9es vous concernant : Il s\u2019agit de la politique de respect de la vie priv\u00e9e adopt\u00e9e par VL-e. Vous disposez d\u2019un droit d\u2019acc\u00e8s, de modification, de rectification et de suppression des donn\u00e9es qui vous concernent (art.34 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading --><h2>Qui sommes-nous\u00a0?<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>L\u2019adresse de notre site est\u00a0: http:\/\/vl-e.fr.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Commentaires<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, ainsi que votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici\u00a0: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>M\u00e9dias<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Cookies<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Utilisation et transmission de vos donn\u00e9es personnelles<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l\u2019e-mail de r\u00e9initialisation.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Dur\u00e9es de stockage de vos donn\u00e9es<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Les droits que vous avez sur vos donn\u00e9es<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Transmission de vos donn\u00e9es personnelles<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p><!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d&#039;\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d&#039;\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/\" \/>\n<meta property=\"og:site_name\" content=\"VL-E\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T15:07:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vl-e.fr\\\/index.php\\\/politique-de-confidentialite-vl-e\\\/\",\"url\":\"https:\\\/\\\/vl-e.fr\\\/index.php\\\/politique-de-confidentialite-vl-e\\\/\",\"name\":\"Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vl-e.fr\\\/#website\"},\"datePublished\":\"2023-05-02T12:02:38+00:00\",\"dateModified\":\"2023-12-20T15:07:05+00:00\",\"description\":\"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d'\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vl-e.fr\\\/index.php\\\/politique-de-confidentialite-vl-e\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vl-e.fr\\\/index.php\\\/politique-de-confidentialite-vl-e\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vl-e.fr\\\/index.php\\\/politique-de-confidentialite-vl-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vl-e.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9 VL-e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vl-e.fr\\\/#website\",\"url\":\"https:\\\/\\\/vl-e.fr\\\/\",\"name\":\"VL-E\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vl-e.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9","description":"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d'\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9","og_description":"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d'\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.","og_url":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/","og_site_name":"VL-E","article_modified_time":"2023-12-20T15:07:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/","url":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/","name":"Politique de confidentialit\u00e9 VL-e Freelance Etudes en \u00e9lectricit\u00e9","isPartOf":{"@id":"https:\/\/vl-e.fr\/#website"},"datePublished":"2023-05-02T12:02:38+00:00","dateModified":"2023-12-20T15:07:05+00:00","description":"D\u00e9couvrez la politique de confidentialit\u00e9 de VL-e. Vos donn\u00e9es sont importantes, notre bureau d'\u00e9tudes en \u00e9lectricit\u00e9 VL-e les respectes.","breadcrumb":{"@id":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vl-e.fr\/index.php\/politique-de-confidentialite-vl-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vl-e.fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9 VL-e"}]},{"@type":"WebSite","@id":"https:\/\/vl-e.fr\/#website","url":"https:\/\/vl-e.fr\/","name":"VL-E","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vl-e.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":8,"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":416,"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/416"}],"wp:attachment":[{"href":"https:\/\/vl-e.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}